{"id":47,"date":"2023-03-22T20:12:32","date_gmt":"2023-03-22T19:12:32","guid":{"rendered":"https:\/\/www.6srl.it\/?page_id=47"},"modified":"2023-03-30T21:40:48","modified_gmt":"2023-03-30T19:40:48","slug":"azienda","status":"publish","type":"page","link":"https:\/\/www.6srl.it\/index.php\/azienda\/","title":{"rendered":"Azienda"},"content":{"rendered":"<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14pt;\"><b>Divisione commerciale e marketing:<\/b><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14pt;\">Si occupa di creare e sviluppare i rapporti commerciali con i Clienti nuovi e acquisiti, allo scopo di raggiungere come obiettivo la soddisfazione del Cliente mediante la creazione di servizi personalizzati ad hoc; promuove i prodotti e i servizi aziendali anche in termini di service; gestisce i reclami; di concerto con la Divisione tecnica ricerca nuove linee di prodotto\/servizio all&#8217;interno della missione aziendale.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14pt;\"><b>Divisione tecnica:<\/b><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14pt;\">Segue lo svolgimento dei lavori a partire dalla fase di progettazione fino alle attivazioni, ai collaudi, all&#8217;assistenza tecnica post-vendita e alla manutenzione degli impianti; studia soluzioni tecnologicamente attuali ed avanzate in linea con le esigenze del Cliente; cura l\u2019aggiornamento professionale del personale tecnico; effettua la selezione dei Fornitori e dei Partners in collaborazione con la Divisione commerciale e marketing.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14pt;\"><b>Divisione amministrativa e personale:<\/b><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14pt;\">segue i rapporti di natura amministrativa e contrattuale con Clienti e Fornitori e si occupa della Direzione del personale<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Divisione commerciale e marketing: Si occupa di creare e sviluppare i rapporti commerciali con i Clienti nuovi e acquisiti, allo scopo di raggiungere come obiettivo la soddisfazione del Cliente mediante la creazione di servizi personalizzati ad hoc; promuove i prodotti e i servizi aziendali anche in termini di service; gestisce i reclami; di concerto con &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.6srl.it\/index.php\/azienda\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Azienda&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":90,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.6srl.it\/index.php\/wp-json\/wp\/v2\/pages\/47"}],"collection":[{"href":"https:\/\/www.6srl.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.6srl.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.6srl.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.6srl.it\/index.php\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":9,"href":"https:\/\/www.6srl.it\/index.php\/wp-json\/wp\/v2\/pages\/47\/revisions"}],"predecessor-version":[{"id":244,"href":"https:\/\/www.6srl.it\/index.php\/wp-json\/wp\/v2\/pages\/47\/revisions\/244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.6srl.it\/index.php\/wp-json\/wp\/v2\/media\/90"}],"wp:attachment":[{"href":"https:\/\/www.6srl.it\/index.php\/wp-json\/wp\/v2\/media?parent=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}